{"id":3722,"count":7,"description":"<h2>Visites priv\u00e9es \u00e0 Salzbourg<\/h2>\r\n<!--Read More-->\r\n\r\nEmbarquez pour un voyage inoubliable \u00e0 travers Salzbourg, joyau baroque de l'Autriche et ville natale de Mozart, o\u00f9 musique, architecture et beaut\u00e9 alpine s'harmonisent \u00e0 la perfection. Avec Tour Travel &amp; More, d\u00e9couvrez la magie de Salzbourg gr\u00e2ce \u00e0 des visites priv\u00e9es personnalis\u00e9es en anglais, con\u00e7ues pour vous faire d\u00e9couvrir l'\u00e9l\u00e9gance culturelle et la grandeur historique de la ville.\r\n<h2><strong>Exploration du c\u0153ur historique de Salzbourg<\/strong><\/h2>\r\nCommencez votre visite priv\u00e9e dans la vieille ville de Salzbourg (Altstadt), class\u00e9e au patrimoine mondial de l'UNESCO, qui regorge d'\u00e9glises orn\u00e9es, de rues m\u00e9di\u00e9vales sinueuses et de places \u00e9l\u00e9gantes. Admirez la grandeur du palais et des jardins de Mirabell, promenez-vous dans la c\u00e9l\u00e8bre Getreidegasse, une charmante rue commer\u00e7ante bord\u00e9e d'enseignes en fer forg\u00e9, et visitez la maison natale de Mozart, un lieu incontournable pour les m\u00e9lomanes.\r\n\r\n\u00c9merveillez-vous devant la cath\u00e9drale de Salzbourg, chef-d'\u0153uvre de l'architecture baroque, et explorez la Residenzplatz, o\u00f9 l'histoire noble de la ville prend vie. Traversez le pont Makartsteg orn\u00e9 de cadenas d'amour et profitez d'une vue imprenable sur la rivi\u00e8re Salzach et les Alpes environnantes.\r\n<h2><strong>Immersion culturelle avec un guide anglophone<\/strong><\/h2>\r\nAvec un riche patrimoine culturel ancr\u00e9 dans la musique et la foi, Salzbourg offre une exploration profonde et enrichissante. Nos guides anglophones experts vous fournissent des informations historiques et des anecdotes qui vous permettront de vous connecter \u00e0 l'\u00e2me de la ville.\r\n\r\nVisitez la forteresse de Hohensalzburg, l'un des ch\u00e2teaux les plus grands et les mieux conserv\u00e9s d'Europe, pour profiter d'une vue panoramique et d\u00e9couvrir des si\u00e8cles d'histoire. Explorez l'abbaye Saint-Pierre, l'un des plus anciens monast\u00e8res du monde germanophone, et d\u00e9couvrez des cours cach\u00e9es, des cimeti\u00e8res anciens et une tranquillit\u00e9 intemporelle.\r\n<h2><strong>Voyage gastronomique \u00e0 travers les saveurs de Salzbourg<\/strong><\/h2>\r\nLaissez vos papilles d\u00e9couvrir les traditions culinaires de Salzbourg lors d'une visite gastronomique priv\u00e9e. D\u00e9gustez des sp\u00e9cialit\u00e9s locales telles que le Salzburger Nockerl, le Wiener Schnitzel et le Kasnocken dans des tavernes authentiques ou des restaurants \u00e9l\u00e9gants.\r\n\r\nD\u00e9gustez des friandises sur le <strong>vieux march\u00e9 (Alter Markt)<\/strong>, savourez un caf\u00e9 autrichien dans des caf\u00e9s historiques tels que le <strong>Caf\u00e9 Tomaselli<\/strong> et essayez les bi\u00e8res locales ou les schnaps. Pour une exp\u00e9rience luxueuse, profitez d'un d\u00eener raffin\u00e9 avec vue sur les Alpes ou d'un d\u00eener au bord de la rivi\u00e8re avec de la musique classique en fond sonore.\r\n<h2><strong>Beaut\u00e9 des paysages et escapades nature<\/strong><\/h2>\r\nLa situation de Salzbourg, entre montagnes et fleuve, offre des paysages infinis. Promenez-vous le long de la promenade du Salzach ou partez en excursion priv\u00e9e dans la campagne environnante. Visitez le ch\u00e2teau de Hellbrunn, c\u00e9l\u00e8bre pour ses fontaines fantaisistes et ses magnifiques jardins.\r\n\r\nNos visites priv\u00e9es peuvent \u00e9galement vous emmener dans la r\u00e9gion des lacs (Salzkammergut), o\u00f9 vous attendent des lacs cristallins et de charmants villages tels que St. Gilgen et St. Wolfgang. En hiver, d\u00e9couvrez les stations alpines voisines ou explorez la magie des march\u00e9s de No\u00ebl de Salzbourg.\r\n<h2><strong>Musique, art et artisanat local<\/strong><\/h2>\r\nDes visites guid\u00e9es sur le th\u00e8me de \u00ab La M\u00e9lodie du bonheur \u00bb aux concerts classiques dans des salles baroques, Salzbourg est synonyme d'excellence musicale. Profitez d'un concert priv\u00e9, visitez le Mozarteum ou explorez les galeries d'art et les boutiques d'artisanat local proposant des articles faits main, des c\u00e9ramiques et des v\u00eatements traditionnels.\r\n\r\nAvec Tour Travel &amp; More, votre visite \u00e0 Salzbourg devient une exp\u00e9rience luxueuse et enrichissante. D\u00e9couvrez le charme intemporel de ce tr\u00e9sor musical et architectural gr\u00e2ce \u00e0 des visites priv\u00e9es alliant histoire, \u00e9l\u00e9gance et confort, guid\u00e9es par des experts locaux qui vous feront d\u00e9couvrir la ville.","link":"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/","name":"Salzbourg","slug":"salzbourg-fr","taxonomy":"product_cat","parent":3709,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3.1 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Salzbourg Tours Privados &#8212; Tour Travel And More<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salzbourg Archives\" \/>\n<meta property=\"og:description\" content=\"Visites priv\u00e9es \u00e0 Salzbourg Embarquez pour un voyage inoubliable \u00e0 travers Salzbourg, joyau baroque de l&#8217;Autriche et ville natale de Mozart, o\u00f9 musique, architecture et beaut\u00e9 alpine s&#8217;harmonisent \u00e0 la perfection. Avec Tour Travel &amp; More, d\u00e9couvrez la magie de Salzbourg gr\u00e2ce \u00e0 des visites priv\u00e9es personnalis\u00e9es en anglais, con\u00e7ues pour vous faire d\u00e9couvrir l&#8217;\u00e9l\u00e9gance culturelle et la grandeur historique de la ville. Exploration du c\u0153ur historique de Salzbourg Commencez votre visite priv\u00e9e dans la vieille ville de Salzbourg (Altstadt), class\u00e9e au patrimoine mondial de l&#8217;UNESCO, qui regorge d&#8217;\u00e9glises orn\u00e9es, de rues m\u00e9di\u00e9vales sinueuses et de places \u00e9l\u00e9gantes. Admirez la grandeur du palais et des jardins de Mirabell, promenez-vous dans la c\u00e9l\u00e8bre Getreidegasse, une charmante rue commer\u00e7ante bord\u00e9e d&#8217;enseignes en fer forg\u00e9, et visitez la maison natale de Mozart, un lieu incontournable pour les m\u00e9lomanes. \u00c9merveillez-vous devant la cath\u00e9drale de Salzbourg, chef-d&#8217;\u0153uvre de l&#8217;architecture baroque, et explorez la Residenzplatz, o\u00f9 l&#8217;histoire noble de la ville prend vie. Traversez le pont Makartsteg orn\u00e9 de cadenas d&#8217;amour et profitez d&#8217;une vue imprenable sur la rivi\u00e8re Salzach et les Alpes environnantes. Immersion culturelle avec un guide anglophone Avec un riche patrimoine culturel ancr\u00e9 dans la musique et la foi, Salzbourg offre une exploration profonde et enrichissante. Nos guides anglophones experts vous fournissent des informations historiques et des anecdotes qui vous permettront de vous connecter \u00e0 l&#8217;\u00e2me de la ville. Visitez la forteresse de Hohensalzburg, l&#8217;un des ch\u00e2teaux les plus grands et les mieux conserv\u00e9s d&#8217;Europe, pour profiter d&#8217;une vue panoramique et d\u00e9couvrir des si\u00e8cles d&#8217;histoire. Explorez l&#8217;abbaye Saint-Pierre, l&#8217;un des plus anciens monast\u00e8res du monde germanophone, et d\u00e9couvrez des cours cach\u00e9es, des cimeti\u00e8res anciens et une tranquillit\u00e9 intemporelle. Voyage gastronomique \u00e0 travers les saveurs de Salzbourg Laissez vos papilles d\u00e9couvrir les traditions culinaires de Salzbourg lors d&#8217;une visite gastronomique priv\u00e9e. D\u00e9gustez des sp\u00e9cialit\u00e9s locales telles que le Salzburger Nockerl, le Wiener Schnitzel et le Kasnocken dans des tavernes authentiques ou des restaurants \u00e9l\u00e9gants. D\u00e9gustez des friandises sur le vieux march\u00e9 (Alter Markt), savourez un caf\u00e9 autrichien dans des caf\u00e9s historiques tels que le Caf\u00e9 Tomaselli et essayez les bi\u00e8res locales ou les schnaps. Pour une exp\u00e9rience luxueuse, profitez d&#8217;un d\u00eener raffin\u00e9 avec vue sur les Alpes ou d&#8217;un d\u00eener au bord de la rivi\u00e8re avec de la musique classique en fond sonore. Beaut\u00e9 des paysages et escapades nature La situation de Salzbourg, entre montagnes et fleuve, offre des paysages infinis. Promenez-vous le long de la promenade du Salzach ou partez en excursion priv\u00e9e dans la campagne environnante. Visitez le ch\u00e2teau de Hellbrunn, c\u00e9l\u00e8bre pour ses fontaines fantaisistes et ses magnifiques jardins. Nos visites priv\u00e9es peuvent \u00e9galement vous emmener dans la r\u00e9gion des lacs (Salzkammergut), o\u00f9 vous attendent des lacs cristallins et de charmants villages tels que St. Gilgen et St. Wolfgang. En hiver, d\u00e9couvrez les stations alpines voisines ou explorez la magie des march\u00e9s de No\u00ebl de Salzbourg. Musique, art et artisanat local Des visites guid\u00e9es sur le th\u00e8me de \u00ab La M\u00e9lodie du bonheur \u00bb aux concerts classiques dans des salles baroques, Salzbourg est synonyme d&#8217;excellence musicale. Profitez d&#8217;un concert priv\u00e9, visitez le Mozarteum ou explorez les galeries d&#8217;art et les boutiques d&#8217;artisanat local proposant des articles faits main, des c\u00e9ramiques et des v\u00eatements traditionnels. Avec Tour Travel &amp; More, votre visite \u00e0 Salzbourg devient une exp\u00e9rience luxueuse et enrichissante. D\u00e9couvrez le charme intemporel de ce tr\u00e9sor musical et architectural gr\u00e2ce \u00e0 des visites priv\u00e9es alliant histoire, \u00e9l\u00e9gance et confort, guid\u00e9es par des experts locaux qui vous feront d\u00e9couvrir la ville.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Tour Travel And More\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TourTravel_More\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/\",\"url\":\"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/\",\"name\":\"Salzbourg Tours Privados &#8212; Tour Travel And More\",\"isPartOf\":{\"@id\":\"https:\/\/tourtravelandmore.com\/fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tourtravelandmore.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L'Autriche\",\"item\":\"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salzbourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tourtravelandmore.com\/fr\/#website\",\"url\":\"https:\/\/tourtravelandmore.com\/fr\/\",\"name\":\"Tour Travel And More\",\"description\":\"Private sightseeing tours and luxury transfers in Spain\",\"publisher\":{\"@id\":\"https:\/\/tourtravelandmore.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tourtravelandmore.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tourtravelandmore.com\/fr\/#organization\",\"name\":\"Tour Travel And More\",\"url\":\"https:\/\/tourtravelandmore.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/tourtravelandmore.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tourtravelandmore.com\/wp-content\/uploads\/2022\/12\/cropped-logo-cabecera-new.png\",\"contentUrl\":\"https:\/\/tourtravelandmore.com\/wp-content\/uploads\/2022\/12\/cropped-logo-cabecera-new.png\",\"width\":430,\"height\":61,\"caption\":\"Tour Travel And More\"},\"image\":{\"@id\":\"https:\/\/tourtravelandmore.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tourtravelandmore\/\",\"https:\/\/x.com\/TourTravel_More\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salzbourg Tours Privados &#8212; Tour Travel And More","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Salzbourg Archives","og_description":"Visites priv\u00e9es \u00e0 Salzbourg Embarquez pour un voyage inoubliable \u00e0 travers Salzbourg, joyau baroque de l&#8217;Autriche et ville natale de Mozart, o\u00f9 musique, architecture et beaut\u00e9 alpine s&#8217;harmonisent \u00e0 la perfection. Avec Tour Travel &amp; More, d\u00e9couvrez la magie de Salzbourg gr\u00e2ce \u00e0 des visites priv\u00e9es personnalis\u00e9es en anglais, con\u00e7ues pour vous faire d\u00e9couvrir l&#8217;\u00e9l\u00e9gance culturelle et la grandeur historique de la ville. Exploration du c\u0153ur historique de Salzbourg Commencez votre visite priv\u00e9e dans la vieille ville de Salzbourg (Altstadt), class\u00e9e au patrimoine mondial de l&#8217;UNESCO, qui regorge d&#8217;\u00e9glises orn\u00e9es, de rues m\u00e9di\u00e9vales sinueuses et de places \u00e9l\u00e9gantes. Admirez la grandeur du palais et des jardins de Mirabell, promenez-vous dans la c\u00e9l\u00e8bre Getreidegasse, une charmante rue commer\u00e7ante bord\u00e9e d&#8217;enseignes en fer forg\u00e9, et visitez la maison natale de Mozart, un lieu incontournable pour les m\u00e9lomanes. \u00c9merveillez-vous devant la cath\u00e9drale de Salzbourg, chef-d&#8217;\u0153uvre de l&#8217;architecture baroque, et explorez la Residenzplatz, o\u00f9 l&#8217;histoire noble de la ville prend vie. Traversez le pont Makartsteg orn\u00e9 de cadenas d&#8217;amour et profitez d&#8217;une vue imprenable sur la rivi\u00e8re Salzach et les Alpes environnantes. Immersion culturelle avec un guide anglophone Avec un riche patrimoine culturel ancr\u00e9 dans la musique et la foi, Salzbourg offre une exploration profonde et enrichissante. Nos guides anglophones experts vous fournissent des informations historiques et des anecdotes qui vous permettront de vous connecter \u00e0 l&#8217;\u00e2me de la ville. Visitez la forteresse de Hohensalzburg, l&#8217;un des ch\u00e2teaux les plus grands et les mieux conserv\u00e9s d&#8217;Europe, pour profiter d&#8217;une vue panoramique et d\u00e9couvrir des si\u00e8cles d&#8217;histoire. Explorez l&#8217;abbaye Saint-Pierre, l&#8217;un des plus anciens monast\u00e8res du monde germanophone, et d\u00e9couvrez des cours cach\u00e9es, des cimeti\u00e8res anciens et une tranquillit\u00e9 intemporelle. Voyage gastronomique \u00e0 travers les saveurs de Salzbourg Laissez vos papilles d\u00e9couvrir les traditions culinaires de Salzbourg lors d&#8217;une visite gastronomique priv\u00e9e. D\u00e9gustez des sp\u00e9cialit\u00e9s locales telles que le Salzburger Nockerl, le Wiener Schnitzel et le Kasnocken dans des tavernes authentiques ou des restaurants \u00e9l\u00e9gants. D\u00e9gustez des friandises sur le vieux march\u00e9 (Alter Markt), savourez un caf\u00e9 autrichien dans des caf\u00e9s historiques tels que le Caf\u00e9 Tomaselli et essayez les bi\u00e8res locales ou les schnaps. Pour une exp\u00e9rience luxueuse, profitez d&#8217;un d\u00eener raffin\u00e9 avec vue sur les Alpes ou d&#8217;un d\u00eener au bord de la rivi\u00e8re avec de la musique classique en fond sonore. Beaut\u00e9 des paysages et escapades nature La situation de Salzbourg, entre montagnes et fleuve, offre des paysages infinis. Promenez-vous le long de la promenade du Salzach ou partez en excursion priv\u00e9e dans la campagne environnante. Visitez le ch\u00e2teau de Hellbrunn, c\u00e9l\u00e8bre pour ses fontaines fantaisistes et ses magnifiques jardins. Nos visites priv\u00e9es peuvent \u00e9galement vous emmener dans la r\u00e9gion des lacs (Salzkammergut), o\u00f9 vous attendent des lacs cristallins et de charmants villages tels que St. Gilgen et St. Wolfgang. En hiver, d\u00e9couvrez les stations alpines voisines ou explorez la magie des march\u00e9s de No\u00ebl de Salzbourg. Musique, art et artisanat local Des visites guid\u00e9es sur le th\u00e8me de \u00ab La M\u00e9lodie du bonheur \u00bb aux concerts classiques dans des salles baroques, Salzbourg est synonyme d&#8217;excellence musicale. Profitez d&#8217;un concert priv\u00e9, visitez le Mozarteum ou explorez les galeries d&#8217;art et les boutiques d&#8217;artisanat local proposant des articles faits main, des c\u00e9ramiques et des v\u00eatements traditionnels. Avec Tour Travel &amp; More, votre visite \u00e0 Salzbourg devient une exp\u00e9rience luxueuse et enrichissante. D\u00e9couvrez le charme intemporel de ce tr\u00e9sor musical et architectural gr\u00e2ce \u00e0 des visites priv\u00e9es alliant histoire, \u00e9l\u00e9gance et confort, guid\u00e9es par des experts locaux qui vous feront d\u00e9couvrir la ville.","og_url":"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/","og_site_name":"Tour Travel And More","twitter_card":"summary_large_image","twitter_site":"@TourTravel_More","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/","url":"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/","name":"Salzbourg Tours Privados &#8212; Tour Travel And More","isPartOf":{"@id":"https:\/\/tourtravelandmore.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/salzbourg-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tourtravelandmore.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L'Autriche","item":"https:\/\/tourtravelandmore.com\/fr\/city\/lautriche-fr\/"},{"@type":"ListItem","position":3,"name":"Salzbourg"}]},{"@type":"WebSite","@id":"https:\/\/tourtravelandmore.com\/fr\/#website","url":"https:\/\/tourtravelandmore.com\/fr\/","name":"Tour Travel And More","description":"Private sightseeing tours and luxury transfers in Spain","publisher":{"@id":"https:\/\/tourtravelandmore.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tourtravelandmore.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tourtravelandmore.com\/fr\/#organization","name":"Tour Travel And More","url":"https:\/\/tourtravelandmore.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tourtravelandmore.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/tourtravelandmore.com\/wp-content\/uploads\/2022\/12\/cropped-logo-cabecera-new.png","contentUrl":"https:\/\/tourtravelandmore.com\/wp-content\/uploads\/2022\/12\/cropped-logo-cabecera-new.png","width":430,"height":61,"caption":"Tour Travel And More"},"image":{"@id":"https:\/\/tourtravelandmore.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tourtravelandmore\/","https:\/\/x.com\/TourTravel_More"]}]}},"_links":{"self":[{"href":"https:\/\/tourtravelandmore.com\/fr\/wp-json\/wp\/v2\/product_cat\/3722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tourtravelandmore.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/tourtravelandmore.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/tourtravelandmore.com\/fr\/wp-json\/wp\/v2\/product_cat\/3709"}],"wp:post_type":[{"href":"https:\/\/tourtravelandmore.com\/fr\/wp-json\/wp\/v2\/product?product_cat=3722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}